{"id":16117,"date":"2019-03-26T06:43:43","date_gmt":"2019-03-26T06:43:43","guid":{"rendered":"https:\/\/urnawp.com\/?page_id=6515"},"modified":"2019-03-26T06:43:43","modified_gmt":"2019-03-26T06:43:43","slug":"contact-form-2","status":"publish","type":"page","link":"https:\/\/h-perfume.com\/ar\/contact-form-2\/","title":{"rendered":"Contact Form"},"content":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1557835181158{padding-top: 50px !important;}&#8221;][vc_column]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f559-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"559\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/16117#wpcf7-f559-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"559\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f559-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-horizontal row\">\n\t<div class=\"col-md-4\">\n\t\t<p><label for=\"name\">Name<span class=\"required\">*<\/span>:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-799\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required required form-control\" id=\"your_name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-799\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-4\">\n\t\t<p><label class=\"control-label\" for=\"email\">Email<span class=\"required\">*<\/span>:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-257\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email required\" id=\"your_email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email-257\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-4\">\n\t\t<p><label for=\"name\">Subject<span class=\"required\">*<\/span>:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-599\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required required form-subject\" id=\"your_subject\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-599\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-12\">\n\t\t<p><label class=\"control-label\" for=\"message\">Message<span class=\"required\">*<\/span>:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-552\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea required\" id=\"your_message\" aria-invalid=\"false\" name=\"textarea-552\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-md-2 col-md-offset-10\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-default\" type=\"submit\" value=\"submit\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"25\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1557835181158{padding-top: 50px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-16117","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/h-perfume.com\/ar\/wp-json\/wp\/v2\/pages\/16117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/h-perfume.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/h-perfume.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/h-perfume.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/h-perfume.com\/ar\/wp-json\/wp\/v2\/comments?post=16117"}],"version-history":[{"count":0,"href":"https:\/\/h-perfume.com\/ar\/wp-json\/wp\/v2\/pages\/16117\/revisions"}],"wp:attachment":[{"href":"https:\/\/h-perfume.com\/ar\/wp-json\/wp\/v2\/media?parent=16117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}